{"id":12651,"date":"2026-01-30T10:27:46","date_gmt":"2026-01-30T09:27:46","guid":{"rendered":"https:\/\/museoimmaginario.net\/immaginario\/?post_type=glossary&#038;p=12651"},"modified":"2026-01-30T10:29:42","modified_gmt":"2026-01-30T09:29:42","slug":"sciocchi","status":"publish","type":"glossary","link":"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/","title":{"rendered":"Sciocchi"},"content":{"rendered":"<p>In ambito semiotico e antropologico, gli &ldquo;<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sciocchi&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In ambito semiotico e antropologico, gli &amp;quot;sciocchi&rdquo; non sono definiti tanto come persone poco intelligenti, ma come una&amp;amp;nbsp;&amp;lt;strong&amp;gt;funzione&amp;lt;\/strong&amp;gt;&amp;amp;nbsp;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione semiotica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;In prospettiva semiotica, lo sciocco &egrave; il personaggio attraverso cui il racconto mette in atto una &amp;quot;legge endogenetica&rdquo; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&ugrave; assurdo, che porta alla messa in questione dell&rsquo;identit&agrave; e del riconoscimento. Lo sciocco &egrave; quindi una funzione linguistico&#8209;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di identit&agrave;\/identificabilit&agrave;.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione antropologica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Dal punto di vista demoetnoantropologico, gli sciocchi (individui o &amp;quot;paesi sciocchi&rdquo;) sono figure attraverso cui una comunit&agrave; esplora i propri confini: ci&ograve; che &egrave; considerato buon senso, ci&ograve; che &egrave; interno\/esterno, chi &egrave; riconosciuto come &amp;quot;dei nostri&rdquo;. Le storie degli sciocchi mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#8209;riconoscimento dell&rsquo;io da parte degli altri e, a volte, dell&rsquo;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &amp;quot;normale&rdquo; (letto, casa, convento). In questo senso, lo sciocco &egrave; un operatore culturale che permette di pensare, ridendo, la fragilit&agrave; dell&rsquo;identit&agrave; personale e sociale.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12652,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>sciocchi<\/a>&rdquo; non sono definiti tanto come persone poco intelligenti, ma come una&nbsp;<strong>funzione<\/strong>&#xA0;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#x200B;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Definizione semiotica<\/h2>\n\n\n\n<p>In prospettiva semiotica, lo sciocco &egrave; il personaggio attraverso cui il racconto mette in atto una &ldquo;legge endogenetica&rdquo; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&ugrave; assurdo, che porta alla messa in questione dell&rsquo;<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Identit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In senso semiotico e antropologico, &amp;quot;identit&agrave;&rdquo; indica il modo in cui un soggetto (persona, gruppo, luogo) viene reso riconoscibile e distinto all&rsquo;interno di un sistema di segni e di relazioni sociali.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva semiotica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; l&rsquo;insieme delle caratteristiche che permettono di identificare &amp;quot;chi &egrave; chi&rdquo; e di mantenerne la continuit&agrave; nel tempo e nello spazio, distinguendo un soggetto da altri soggetti sulla base di tratti riconoscibili. Non &egrave; solo un contenuto psicologico, ma un effetto di configurazioni narrative, spaziali, discorsive (nome, corpo, posizione nello spazio domestico, relazioni), che possono entrare in crisi producendo problemi di identit&agrave;\/identificabilit&agrave;.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva antropologica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; un processo dinamico di definizione di s&eacute; e degli altri, attraverso appartenenze (famiglia, paese, etnia, nazione) e confini simbolici che separano &amp;quot;noi&rdquo; da &amp;quot;loro&rdquo;. Comprende dimensioni personali e collettive: si costruisce narrativamente, attraverso pratiche, memorie, luoghi, e pu&ograve; essere oggetto di conflitto, negoziazione, ridefinizione continua, pi&ugrave; che una sostanza fissa o essenza immutabile.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12656,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/identita\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>identit&agrave;<\/a> e del riconoscimento. Lo sciocco &egrave; quindi una funzione linguistico&#8209;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Identit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In senso semiotico e antropologico, &amp;quot;identit&agrave;&rdquo; indica il modo in cui un soggetto (persona, gruppo, luogo) viene reso riconoscibile e distinto all&rsquo;interno di un sistema di segni e di relazioni sociali.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva semiotica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; l&rsquo;insieme delle caratteristiche che permettono di identificare &amp;quot;chi &egrave; chi&rdquo; e di mantenerne la continuit&agrave; nel tempo e nello spazio, distinguendo un soggetto da altri soggetti sulla base di tratti riconoscibili. Non &egrave; solo un contenuto psicologico, ma un effetto di configurazioni narrative, spaziali, discorsive (nome, corpo, posizione nello spazio domestico, relazioni), che possono entrare in crisi producendo problemi di identit&agrave;\/identificabilit&agrave;.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva antropologica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; un processo dinamico di definizione di s&eacute; e degli altri, attraverso appartenenze (famiglia, paese, etnia, nazione) e confini simbolici che separano &amp;quot;noi&rdquo; da &amp;quot;loro&rdquo;. Comprende dimensioni personali e collettive: si costruisce narrativamente, attraverso pratiche, memorie, luoghi, e pu&ograve; essere oggetto di conflitto, negoziazione, ridefinizione continua, pi&ugrave; che una sostanza fissa o essenza immutabile.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12656,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/identita\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>identit&agrave;<\/a>\/identificabilit&agrave;.&#8203;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Definizione antropologica<\/h2>\n\n\n\n<p>Dal punto di vista demoetnoantropologico, gli <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sciocchi&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In ambito semiotico e antropologico, gli &amp;quot;sciocchi&rdquo; non sono definiti tanto come persone poco intelligenti, ma come una&amp;amp;nbsp;&amp;lt;strong&amp;gt;funzione&amp;lt;\/strong&amp;gt;&amp;amp;nbsp;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione semiotica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;In prospettiva semiotica, lo sciocco &egrave; il personaggio attraverso cui il racconto mette in atto una &amp;quot;legge endogenetica&rdquo; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&ugrave; assurdo, che porta alla messa in questione dell&rsquo;identit&agrave; e del riconoscimento. Lo sciocco &egrave; quindi una funzione linguistico&#8209;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di identit&agrave;\/identificabilit&agrave;.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione antropologica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Dal punto di vista demoetnoantropologico, gli sciocchi (individui o &amp;quot;paesi sciocchi&rdquo;) sono figure attraverso cui una comunit&agrave; esplora i propri confini: ci&ograve; che &egrave; considerato buon senso, ci&ograve; che &egrave; interno\/esterno, chi &egrave; riconosciuto come &amp;quot;dei nostri&rdquo;. Le storie degli sciocchi mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#8209;riconoscimento dell&rsquo;io da parte degli altri e, a volte, dell&rsquo;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &amp;quot;normale&rdquo; (letto, casa, convento). In questo senso, lo sciocco &egrave; un operatore culturale che permette di pensare, ridendo, la fragilit&agrave; dell&rsquo;identit&agrave; personale e sociale.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12652,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>sciocchi<\/a> (individui o &ldquo;paesi <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sciocchi&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In ambito semiotico e antropologico, gli &amp;quot;sciocchi&rdquo; non sono definiti tanto come persone poco intelligenti, ma come una&amp;amp;nbsp;&amp;lt;strong&amp;gt;funzione&amp;lt;\/strong&amp;gt;&amp;amp;nbsp;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione semiotica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;In prospettiva semiotica, lo sciocco &egrave; il personaggio attraverso cui il racconto mette in atto una &amp;quot;legge endogenetica&rdquo; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&ugrave; assurdo, che porta alla messa in questione dell&rsquo;identit&agrave; e del riconoscimento. Lo sciocco &egrave; quindi una funzione linguistico&#8209;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di identit&agrave;\/identificabilit&agrave;.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione antropologica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Dal punto di vista demoetnoantropologico, gli sciocchi (individui o &amp;quot;paesi sciocchi&rdquo;) sono figure attraverso cui una comunit&agrave; esplora i propri confini: ci&ograve; che &egrave; considerato buon senso, ci&ograve; che &egrave; interno\/esterno, chi &egrave; riconosciuto come &amp;quot;dei nostri&rdquo;. Le storie degli sciocchi mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#8209;riconoscimento dell&rsquo;io da parte degli altri e, a volte, dell&rsquo;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &amp;quot;normale&rdquo; (letto, casa, convento). In questo senso, lo sciocco &egrave; un operatore culturale che permette di pensare, ridendo, la fragilit&agrave; dell&rsquo;identit&agrave; personale e sociale.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12652,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>sciocchi<\/a>&rdquo;) sono figure attraverso cui una comunit&agrave; esplora i propri confini: ci&ograve; che &egrave; considerato buon senso, ci&ograve; che &egrave; interno\/esterno, chi &egrave; riconosciuto come &ldquo;dei nostri&rdquo;. Le storie degli <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sciocchi&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In ambito semiotico e antropologico, gli &amp;quot;sciocchi&rdquo; non sono definiti tanto come persone poco intelligenti, ma come una&amp;amp;nbsp;&amp;lt;strong&amp;gt;funzione&amp;lt;\/strong&amp;gt;&amp;amp;nbsp;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione semiotica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;In prospettiva semiotica, lo sciocco &egrave; il personaggio attraverso cui il racconto mette in atto una &amp;quot;legge endogenetica&rdquo; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&ugrave; assurdo, che porta alla messa in questione dell&rsquo;identit&agrave; e del riconoscimento. Lo sciocco &egrave; quindi una funzione linguistico&#8209;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di identit&agrave;\/identificabilit&agrave;.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione antropologica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Dal punto di vista demoetnoantropologico, gli sciocchi (individui o &amp;quot;paesi sciocchi&rdquo;) sono figure attraverso cui una comunit&agrave; esplora i propri confini: ci&ograve; che &egrave; considerato buon senso, ci&ograve; che &egrave; interno\/esterno, chi &egrave; riconosciuto come &amp;quot;dei nostri&rdquo;. Le storie degli sciocchi mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#8209;riconoscimento dell&rsquo;io da parte degli altri e, a volte, dell&rsquo;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &amp;quot;normale&rdquo; (letto, casa, convento). In questo senso, lo sciocco &egrave; un operatore culturale che permette di pensare, ridendo, la fragilit&agrave; dell&rsquo;identit&agrave; personale e sociale.&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12652,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>sciocchi<\/a> mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#8209;riconoscimento dell&rsquo;io da parte degli altri e, a volte, dell&rsquo;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &ldquo;normale&rdquo; (letto, casa, convento). In questo senso, lo sciocco &egrave; un operatore culturale che permette di pensare, ridendo, la fragilit&agrave; dell&rsquo;<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Identit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In senso semiotico e antropologico, &amp;quot;identit&agrave;&rdquo; indica il modo in cui un soggetto (persona, gruppo, luogo) viene reso riconoscibile e distinto all&rsquo;interno di un sistema di segni e di relazioni sociali.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva semiotica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; l&rsquo;insieme delle caratteristiche che permettono di identificare &amp;quot;chi &egrave; chi&rdquo; e di mantenerne la continuit&agrave; nel tempo e nello spazio, distinguendo un soggetto da altri soggetti sulla base di tratti riconoscibili. Non &egrave; solo un contenuto psicologico, ma un effetto di configurazioni narrative, spaziali, discorsive (nome, corpo, posizione nello spazio domestico, relazioni), che possono entrare in crisi producendo problemi di identit&agrave;\/identificabilit&agrave;.&#8203;&#8203;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;strong&amp;gt;In prospettiva antropologica&amp;lt;\/strong&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Identit&agrave; &egrave; un processo dinamico di definizione di s&eacute; e degli altri, attraverso appartenenze (famiglia, paese, etnia, nazione) e confini simbolici che separano &amp;quot;noi&rdquo; da &amp;quot;loro&rdquo;. Comprende dimensioni personali e collettive: si costruisce narrativamente, attraverso pratiche, memorie, luoghi, e pu&ograve; essere oggetto di conflitto, negoziazione, ridefinizione continua, pi&ugrave; che una sostanza fissa o essenza immutabile.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12656,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/identita\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>identit&agrave;<\/a> personale e sociale.&#8203;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/museoimmaginario.net\/immaginario\/wp-content\/uploads\/2026\/01\/Sciocchi-NAtti.jpg\" alt=\"\" class=\"wp-image-12652\" srcset=\"https:\/\/museoimmaginario.net\/immaginario\/wp-content\/uploads\/2026\/01\/Sciocchi-NAtti.jpg 1024w, https:\/\/museoimmaginario.net\/immaginario\/wp-content\/uploads\/2026\/01\/Sciocchi-NAtti-300x300.jpg 300w, https:\/\/museoimmaginario.net\/immaginario\/wp-content\/uploads\/2026\/01\/Sciocchi-NAtti-150x150.jpg 150w, https:\/\/museoimmaginario.net\/immaginario\/wp-content\/uploads\/2026\/01\/Sciocchi-NAtti-768x768.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In ambito semiotico e antropologico, gli &#x201C;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sciocchi&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;In ambito semiotico e antropologico, gli &amp;quot;sciocchi&#x201D; non sono definiti tanto come persone poco intelligenti, ma come una&amp;amp;nbsp;&amp;lt;strong&amp;gt;funzione&amp;lt;\/strong&amp;gt;&amp;amp;nbsp;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#x200B;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione semiotica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;In prospettiva semiotica, lo sciocco &#xE8; il personaggio attraverso cui il racconto mette in atto una &amp;quot;legge endogenetica&#x201D; di svolgimento: a partire da un evento banale, la narrazione si sviluppa da sola secondo un circolo vizioso sempre pi&#xF9; assurdo, che porta alla messa in questione dell&#x2019;identit&#xE0; e del riconoscimento. Lo sciocco &#xE8; quindi una funzione linguistico&#x2011;folklorica, non un semplice tratto psicologico: serve a mostrare come il significato possa deviare, biforcarsi, produrre catastrofi di identit&#xE0;\/identificabilit&#xE0;.&#x200B;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:heading --&amp;gt;Definizione antropologica&amp;lt;!-- \/wp:heading --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;Dal punto di vista demoetnoantropologico, gli sciocchi (individui o &amp;quot;paesi sciocchi&#x201D;) sono figure attraverso cui una comunit&#xE0; esplora i propri confini: ci&#xF2; che &#xE8; considerato buon senso, ci&#xF2; che &#xE8; interno\/esterno, chi &#xE8; riconosciuto come &amp;quot;dei nostri&#x201D;. Le storie degli sciocchi mettono in scena errori di logica pratica, fraintendimenti e travestimenti che portano al non&#x2011;riconoscimento dell&#x2019;io da parte degli altri e, a volte, dell&#x2019;io stesso, spesso legando questa crisi allo spostamento fuori dallo spazio domestico &amp;quot;normale&#x201D; (letto, casa, convento). In questo senso, lo sciocco &#xE8; un operatore culturale che permette di pensare, ridendo, la fragilit&#xE0; dell&#x2019;identit&#xE0; personale e sociale.&#x200B;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:image {&amp;quot;id&amp;quot;:12652,&amp;quot;sizeSlug&amp;quot;:&amp;quot;full&amp;quot;,&amp;quot;linkDestination&amp;quot;:&amp;quot;none&amp;quot;} --&amp;gt;&amp;lt;figure class=&amp;quot;wp-block-image size-full&amp;quot;&amp;gt;&amp;lt;\/figure&amp;gt;&amp;lt;!-- \/wp:image --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/museoimmaginario.net\/immaginario\/glossario\/sciocchi\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">sciocchi<\/a>&#x201D; non sono definiti tanto come persone poco intelligenti, ma come una&#xA0;funzione&#xA0;narrativa e culturale che fa emergere, in forma comica, i limiti e le crisi dei meccanismi di senso condivisi.&#x200B; Definizione semiotica In prospettiva semiotica, lo sciocco &#xE8; il personaggio attraverso cui il racconto mette in atto una &#x201C;legge&#x2026;<\/p>\n","protected":false},"author":10,"featured_media":0,"menu_order":0,"template":"","meta":{"ngg_post_thumbnail":0,"_themeisle_gutenberg_block_has_review":false,"h5ap_radio_sources":[],"_tbt_post_transparent":"","_tbt_post_title":"","_tbt_post_layout":"","_tbt_post_sidebar_id":"","_tbt_post_content_style":"","_tbt_post_vertical_padding":"","_tbt_post_feature":"","_tbt_post_feature_position":"","_tbt_post_header":false,"_tbt_post_footer":false,"footnotes":""},"class_list":["post-12651","glossary","type-glossary","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/glossary\/12651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":2,"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/glossary\/12651\/revisions"}],"predecessor-version":[{"id":12654,"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/glossary\/12651\/revisions\/12654"}],"wp:attachment":[{"href":"https:\/\/museoimmaginario.net\/immaginario\/wp-json\/wp\/v2\/media?parent=12651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}